{"id":129,"date":"2022-02-03T06:34:30","date_gmt":"2022-02-03T06:34:30","guid":{"rendered":"https:\/\/iris.com.pk\/v5\/?page_id=129"},"modified":"2022-10-22T12:22:24","modified_gmt":"2022-10-22T12:22:24","slug":"about-us","status":"publish","type":"page","link":"https:\/\/iris.com.pk\/index.php\/about-us\/","title":{"rendered":"About Us"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"129\" class=\"elementor elementor-129\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-df701d2 elementor-section-content-middle elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"df701d2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5b480fa elementor-hidden-phone\" data-id=\"5b480fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-acb2b25 elementor-icon-list--layout-inline elementor-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"acb2b25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@iris.com.pk<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3beda19\" data-id=\"3beda19\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-03dff32 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"03dff32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/goo.gl\/maps\/YydVQSEKh6APDjpk6\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-map-marker\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">43-10-e Dr. Mahmood Husain Road, Block 6 PECHS, Karachi, Karachi City, Sindh 75400<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3c19160\" data-id=\"3c19160\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6caf18a elementor-widget__width-auto elementor-widget elementor-widget-elementskit-social-media\" data-id=\"6caf18a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-social-media.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t\t <ul class=\"ekit_social_media\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-f392861\">\n\t\t\t\t\t    <a\n\t\t\t\t\t\thref=\"#\" aria-label=\"Facebook\" class=\"facebook\" >\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-facebook\"><\/i>\n                                                                                                            <\/a>\n                    <\/li>\n                    \t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-2f3c4eb\">\n\t\t\t\t\t    <a\n\t\t\t\t\t\thref=\"#\" aria-label=\"Linkedin\" class=\"linkedin\" >\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-linkedin\"><\/i>\n                                                                                                            <\/a>\n                    <\/li>\n                    \t\t\t\t\t\t\t<\/ul>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-83d065c elementor-section-content-middle elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-section-height-default elementor-section-height-default\" data-id=\"83d065c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-34ac209 elementor-hidden-phone\" data-id=\"34ac209\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8ae00d elementor-icon-list--layout-inline elementor-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d8ae00d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@iris.com.pk<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3ed6c3a\" data-id=\"3ed6c3a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3642f1a\" data-id=\"3642f1a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67ec2cd elementor-widget__width-auto elementor-widget elementor-widget-elementskit-social-media\" data-id=\"67ec2cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-social-media.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t\t <ul class=\"ekit_social_media\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-f392861\">\n\t\t\t\t\t    <a\n\t\t\t\t\t\thref=\"#\" aria-label=\"Facebook\" class=\"facebook\" >\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-facebook\"><\/i>\n                                                                                                            <\/a>\n                    <\/li>\n                    \t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-2f3c4eb\">\n\t\t\t\t\t    <a\n\t\t\t\t\t\thref=\"#\" aria-label=\"Linkedin\" class=\"linkedin\" >\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-linkedin\"><\/i>\n                                                                                                            <\/a>\n                    <\/li>\n                    \t\t\t\t\t\t\t<\/ul>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-400b593 elementor-section-content-middle elementor-section-full_width elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"400b593\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b00900e\" data-id=\"b00900e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7be0351 elementor-widget elementor-widget-image\" data-id=\"7be0351\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"416\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/07\/Untitled-1-01-1-e1657188070788-768x416.jpg\" class=\"attachment-medium_large size-medium_large wp-image-3513\" alt=\"\" srcset=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/07\/Untitled-1-01-1-e1657188070788-768x416.jpg 768w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/07\/Untitled-1-01-1-e1657188070788-300x163.jpg 300w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/07\/Untitled-1-01-1-e1657188070788.jpg 1000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a55406d\" data-id=\"a55406d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c414703 elementor-widget elementor-widget-heading\" data-id=\"c414703\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">THE SENSE OF EXCELLENCE IN WORK<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5b772c7 elementor-hidden-desktop\" data-id=\"5b772c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24b5c97 hfe-nav-menu__align-left hfe-submenu-icon-arrow hfe-submenu-animation-none hfe-link-redirect-child hfe-nav-menu__breakpoint-tablet elementor-widget elementor-widget-navigation-menu\" data-id=\"24b5c97\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;toggle_border_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;toggle_border_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;toggle_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;toggle_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_row_space&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_row_space_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_row_space_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;dropdown_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;width_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;220&quot;,&quot;sizes&quot;:[]},&quot;width_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;width_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"navigation-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"hfe-nav-menu hfe-layout-horizontal hfe-nav-menu-layout horizontal hfe-pointer__none\" data-layout=\"horizontal\">\n\t\t\t\t<div role=\"button\" class=\"hfe-nav-menu__toggle elementor-clickable\" tabindex=\"0\" aria-label=\"Menu Toggle\">\n\t\t\t\t\t<span class=\"screen-reader-text\">Menu<\/span>\n\t\t\t\t\t<div class=\"hfe-nav-menu-icon\">\n\t\t\t\t\t\t<i aria-hidden=\"true\"  class=\"fas fa-align-justify\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<nav class=\"hfe-nav-menu__layout-horizontal hfe-nav-menu__submenu-arrow\" data-toggle-icon=\"&lt;i aria-hidden=&quot;true&quot; tabindex=&quot;0&quot; class=&quot;fas fa-align-justify&quot;&gt;&lt;\/i&gt;\" data-close-icon=\"&lt;i aria-hidden=&quot;true&quot; tabindex=&quot;0&quot; class=&quot;far fa-window-close&quot;&gt;&lt;\/i&gt;\" data-full-width=\"yes\">\n\t\t\t\t\t<ul id=\"menu-1-24b5c97\" class=\"hfe-nav-menu\"><li id=\"menu-item-1154\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home parent hfe-creative-menu\"><a href=\"https:\/\/iris.com.pk\/\" class = \"hfe-menu-item\">Home<\/a><\/li>\n<li id=\"menu-item-166\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/iris.com.pk\/index.php\/about-us\/\" class = \"hfe-menu-item\">About Us<\/a><\/li>\n<li id=\"menu-item-5140\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children parent hfe-has-submenu hfe-creative-menu\"><div class=\"hfe-has-submenu-container\" tabindex=\"0\" role=\"button\" aria-haspopup=\"true\" aria-expanded=\"false\"><a href=\"https:\/\/iris.com.pk\/index.php\/our-portfolio\/\" class = \"hfe-menu-item\">Our portfolio<span class='hfe-menu-toggle sub-arrow hfe-menu-child-0'><i class='fa'><\/i><\/span><\/a><\/div>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-5141\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/iris.com.pk\/index.php\/product-supplier\/\" class = \"hfe-sub-menu-item\">Product<\/a><\/li>\n\t<li id=\"menu-item-4831\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/iris.com.pk\/index.php\/services\/\" class = \"hfe-sub-menu-item\">Services<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-4740\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/iris.com.pk\/index.php\/our-partners\/\" class = \"hfe-menu-item\">Our Partners<\/a><\/li>\n<li id=\"menu-item-4929\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/iris.com.pk\/index.php\/events-2-2\/\" class = \"hfe-menu-item\">Events<\/a><\/li>\n<li id=\"menu-item-259\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/iris.com.pk\/index.php\/contact-us\/\" class = \"hfe-menu-item\">Contact Us<\/a><\/li>\n<\/ul> \n\t\t\t\t<\/nav>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9610f40 elementor-section-content-middle elementor-section-full_width elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"9610f40\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8ffbd91\" data-id=\"8ffbd91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3715145 elementor-widget elementor-widget-image\" data-id=\"3715145\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"416\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/07\/Untitled-1-01-1-e1657188070788-768x416.jpg\" class=\"attachment-medium_large size-medium_large wp-image-3513\" alt=\"\" srcset=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/07\/Untitled-1-01-1-e1657188070788-768x416.jpg 768w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/07\/Untitled-1-01-1-e1657188070788-300x163.jpg 300w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/07\/Untitled-1-01-1-e1657188070788.jpg 1000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2998932\" data-id=\"2998932\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86ace13 elementor-widget elementor-widget-heading\" data-id=\"86ace13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">THE SENSE OF EXCELLENCE IN WORK<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c42178d elementor-hidden-mobile elementor-hidden-tablet\" data-id=\"c42178d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ed8479 elementor-widget elementor-widget-ekit-nav-menu\" data-id=\"8ed8479\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ekit-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<nav class=\"ekit-wid-con ekit_menu_responsive_mobile\"\n\t\t\tdata-hamburger-icon=\"icon icon-menu-11\"\n\t\t\tdata-hamburger-icon-type=\"icon\"\n\t\t\tdata-responsive-breakpoint=\"767\"\n\t\t\tdata-close-on-anchor=\"no\">\n\t\t\t            <button class=\"elementskit-menu-hamburger elementskit-menu-toggler\"  type=\"button\" aria-label=\"hamburger-icon\">\n                <i aria-hidden=\"true\" class=\"ekit-menu-icon icon icon-menu-11\"><\/i>            <\/button>\n            <div id=\"ekit-megamenu-header-menu\" class=\"elementskit-menu-container elementskit-menu-offcanvas-elements elementskit-navbar-nav-default ekit-nav-menu-one-page- ekit-nav-dropdown-click\"><ul id=\"menu-header-menu\" class=\"elementskit-navbar-nav elementskit-menu-po-right submenu-click-on-icon\"><li id=\"menu-item-1154\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-1154 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/iris.com.pk\/\" class=\"ekit-menu-nav-link\">Home<\/a><\/li>\n<li id=\"menu-item-166\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-166 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/iris.com.pk\/index.php\/about-us\/\" class=\"ekit-menu-nav-link\">About Us<\/a><\/li>\n<li id=\"menu-item-5140\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-5140 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/iris.com.pk\/index.php\/our-portfolio\/\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Our portfolio<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-5141\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5141 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/iris.com.pk\/index.php\/product-supplier\/\" class=\" dropdown-item\">Product<\/a>\t<li id=\"menu-item-4831\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4831 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/iris.com.pk\/index.php\/services\/\" class=\" dropdown-item\">Services<\/a><\/ul>\n<\/li>\n<li id=\"menu-item-4740\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4740 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/iris.com.pk\/index.php\/our-partners\/\" class=\"ekit-menu-nav-link\">Our Partners<\/a><\/li>\n<li id=\"menu-item-4929\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4929 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/iris.com.pk\/index.php\/events-2-2\/\" class=\"ekit-menu-nav-link\">Events<\/a><\/li>\n<li id=\"menu-item-259\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-259 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/iris.com.pk\/index.php\/contact-us\/\" class=\"ekit-menu-nav-link\">Contact Us<\/a><\/li>\n<\/ul><div class=\"elementskit-nav-identity-panel\"><a class=\"elementskit-nav-logo\" href=\"https:\/\/iris.com.pk\" target=\"\" rel=\"\"><img src=\"https:\/\/iris.com.pk\/v5\/wp-content\/uploads\/2022\/02\/iris_3-removebg-preview.png\" title=\"iris_3-removebg-preview\" alt=\"iris_3-removebg-preview\" decoding=\"async\" \/><\/a><button class=\"elementskit-menu-close elementskit-menu-toggler\" type=\"button\">X<\/button><\/div><\/div>\n\t\t\t<div class=\"elementskit-menu-overlay elementskit-menu-offcanvas-elements elementskit-menu-toggler ekit-nav-menu--overlay\"><\/div>        <\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f534985 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f534985\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-53ad4a8\" data-id=\"53ad4a8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-915d6a6 elementor-widget elementor-widget-heading\" data-id=\"915d6a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ABOUT US<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-da5bd3b elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"da5bd3b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-612e7d8\" data-id=\"612e7d8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-051b017 e-transform elementor-widget elementor-widget-image\" data-id=\"051b017\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_skewY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-20,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-09-at-4.42.22-PM-768x1024.jpeg\" class=\"attachment-large size-large wp-image-4614\" alt=\"\" srcset=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-09-at-4.42.22-PM-768x1024.jpeg 768w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-09-at-4.42.22-PM-225x300.jpeg 225w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-09-at-4.42.22-PM.jpeg 960w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1f0774f\" data-id=\"1f0774f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-00ea3e3 e-transform elementor-widget elementor-widget-image\" data-id=\"00ea3e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_skewY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-09-at-4.42.21-PM-768x1024.jpeg\" class=\"attachment-large size-large wp-image-4612\" alt=\"\" srcset=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-09-at-4.42.21-PM-768x1024.jpeg 768w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-09-at-4.42.21-PM-225x300.jpeg 225w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-09-at-4.42.21-PM.jpeg 960w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-965e731\" data-id=\"965e731\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0a86ee e-transform elementor-widget elementor-widget-image\" data-id=\"e0a86ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_skewY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-20,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-09-at-4.42.20-PM-768x1024.jpeg\" class=\"attachment-large size-large wp-image-4611\" alt=\"\" srcset=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-09-at-4.42.20-PM-768x1024.jpeg 768w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-09-at-4.42.20-PM-225x300.jpeg 225w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-09-at-4.42.20-PM.jpeg 960w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-03515ae\" data-id=\"03515ae\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1da448 e-transform elementor-widget elementor-widget-image\" data-id=\"a1da448\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_skewY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-09-at-4.42.23-PM-768x1024.jpeg\" class=\"attachment-large size-large wp-image-4615\" alt=\"\" srcset=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-09-at-4.42.23-PM-768x1024.jpeg 768w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-09-at-4.42.23-PM-225x300.jpeg 225w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-09-at-4.42.23-PM.jpeg 960w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d6ef112 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d6ef112\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-81acaf3 elementor-invisible\" data-id=\"81acaf3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;pulse&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-927028e ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"927028e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"#\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                            <div class=\"elementskit-box-header\">\n                <div class=\"elementskit-info-box-icon \">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/info.png\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/info.png 512w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/info-300x300.png 300w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/info-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>                <\/div>\n          <\/div>\n                <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    ABOUT US                <\/h3>\n                                            <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-7598424\" data-id=\"7598424\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93ed69f elementor-widget elementor-widget-text-editor\" data-id=\"93ed69f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Since 2006, IRIS INTERNATIONAL has served as a guide in facilitation of the Pharmaceutical, Health, Food, and Petrochemical Industries of Pakistan. An enterprise well-known for expediting material transactions, IRIS INTERNATIONAL warmly opens its doors to new business avenues and opportunities as they come.<\/p><p><br \/>With the Board of Directors holding out a keen eye in search of talent and potential, the Indenting firm hones both young and veteran individuals into experts of their respective fields that ultimately provide many key services for the firm.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7681250 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7681250\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ab7a969\" data-id=\"ab7a969\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8da5ac elementor-widget elementor-widget-heading\" data-id=\"b8da5ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">I<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-0aa7523\" data-id=\"0aa7523\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f03c1a8 elementor-widget elementor-widget-heading\" data-id=\"f03c1a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NSPIRE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ba2db8 elementor-widget elementor-widget-text-editor\" data-id=\"3ba2db8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>An integral part of our daily grind, We believe in our team; just as much as they believe in us. This mutual trust has blossomed our workspace into a &#8216;safe space&#8217;, where our best shine the brightest.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10cb78a elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10cb78a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f125f13\" data-id=\"f125f13\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16a56fe elementor-widget elementor-widget-heading\" data-id=\"16a56fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">R<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-961686e\" data-id=\"961686e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd1f189 elementor-widget elementor-widget-heading\" data-id=\"cd1f189\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">EPRESENT<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c303b93 elementor-widget elementor-widget-text-editor\" data-id=\"c303b93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The finest associates across the globe. We are after all, a Business Development Enterprise. We relish opportunities to represent our client, the best we can. If the brand is our identity; the client IS the brand. It&#8217;s just that simple!\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ce2219d elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ce2219d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b0a1cd3\" data-id=\"b0a1cd3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-769f821 elementor-widget elementor-widget-heading\" data-id=\"769f821\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">I<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-c087b20\" data-id=\"c087b20\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f732228 elementor-widget elementor-widget-heading\" data-id=\"f732228\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MAGINE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-682042b elementor-widget elementor-widget-text-editor\" data-id=\"682042b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Beyond the usual parameters of success. The irony is that stepping into unfamiliar territory, isn&#8217;t quite an unfamiliar advent for us. Extending our potential to new horizons is what makes us stand out of the crowd.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39a3258 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39a3258\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ad6dc40\" data-id=\"ad6dc40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ced78cb elementor-widget elementor-widget-heading\" data-id=\"ced78cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">S<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-7943423\" data-id=\"7943423\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a98347 elementor-widget elementor-widget-heading\" data-id=\"8a98347\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">USTAIN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23f761c elementor-widget elementor-widget-text-editor\" data-id=\"23f761c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Relationships<\/strong> where would we be without our partners? Gratitude is key in all walks of life, and our walk is a sprint! We breathe connection. From creating new relationships to maintaining the old, our journeys come without destinations. And we like it that way<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12e1e17 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12e1e17\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-febe79b\" data-id=\"febe79b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fda4767 elementor-widget elementor-widget-spacer\" data-id=\"fda4767\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a58596a elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"a58596a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52cfe06\" data-id=\"52cfe06\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abfc78c elementor-widget elementor-widget-text-editor\" data-id=\"abfc78c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>With the Board of Directors holding out a keen eye in search of talent and potential, the Indenting firm hones both young and veteran individuals into experts of their respective fields that provide many key services for the firm. Boasting a panel of qualified pharmacists, our homework on the client\u2019s needs is always second to none.<\/p><p><br \/>At Iris International, we believe in providing to the fullest, showing zero compromise on facilitation of quality. This is exactly why our valued staff has been equipped with state-of-the-art facilities and modern-day infrastructural means. The ultimate idea is to achieve \u2018more\u2019, by aiding our Human Resource in realizing its massive, untapped potential.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b5ea8a elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"5b5ea8a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c8e7b1f\" data-id=\"c8e7b1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd1b1eb elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"fd1b1eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our Business Partner<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e92e68 elementor-widget elementor-widget-elementskit-client-logo\" data-id=\"9e92e68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-client-logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"elementskit-clients-slider slider-dotted dot_dotted simple_logo_image\" data-config=\"{&quot;rtl&quot;:false,&quot;arrows&quot;:false,&quot;dots&quot;:true,&quot;autoplay&quot;:true,&quot;speed&quot;:1000,&quot;slidesPerView&quot;:4,&quot;slidesPerGroup&quot;:3,&quot;pauseOnHover&quot;:true,&quot;loop&quot;:false,&quot;breakpoints&quot;:{&quot;320&quot;:{&quot;slidesPerView&quot;:1,&quot;slidesPerGroup&quot;:1,&quot;spaceBetween&quot;:10},&quot;768&quot;:{&quot;slidesPerView&quot;:2,&quot;slidesPerGroup&quot;:1,&quot;spaceBetween&quot;:10},&quot;1024&quot;:{&quot;slidesPerView&quot;:4,&quot;slidesPerGroup&quot;:3,&quot;spaceBetween&quot;:15}}}\" data-direction=\"\">\n\t\t\t<div class=\"ekit-main-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-client-slider-item swiper-slide \">\n\t\t\t\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t\t\t\t<div class=\"single-client image-switcher\" title=\"Fermenta Biotech Limited\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-image\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"180\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/Untitled-design-8-300x300_180x180.png\" class=\"\" alt=\"\" srcset=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/Untitled-design-8-300x300_180x180.png 180w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/Untitled-design-8-300x300_180x180-150x150.png 150w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-client-slider-item swiper-slide \">\n\t\t\t\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t\t\t\t<div class=\"single-client image-switcher\" title=\"Haibin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-image\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"180\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/LOG_10110315425914-comp243600-1.jpg\" class=\"\" alt=\"\" srcset=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/LOG_10110315425914-comp243600-1.jpg 180w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/LOG_10110315425914-comp243600-1-150x150.jpg 150w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-client-slider-item swiper-slide \">\n\t\t\t\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t\t\t\t<div class=\"single-client image-switcher\" title=\"Nectar\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-image\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"180\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/42be5d77efcd851165dfb59b91a1142c_180x180.jpg\" class=\"\" alt=\"\" srcset=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/42be5d77efcd851165dfb59b91a1142c_180x180.jpg 180w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/42be5d77efcd851165dfb59b91a1142c_180x180-150x150.jpg 150w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-client-slider-item swiper-slide \">\n\t\t\t\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t\t\t\t<div class=\"single-client image-switcher\" title=\"Chemo\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-image\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"180\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/Chemo-logo-300x195_180x180.gif\" class=\"\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-client-slider-item swiper-slide \">\n\t\t\t\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t\t\t\t<div class=\"single-client image-switcher\" title=\"teva\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-image\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"180\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/download_1_180x180.png\" class=\"\" alt=\"\" srcset=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/download_1_180x180.png 180w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/download_1_180x180-150x150.png 150w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-client-slider-item swiper-slide \">\n\t\t\t\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t\t\t\t<div class=\"single-client image-switcher\" title=\"Guobang Pharma\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-image\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"157\" height=\"67\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/1635582349678_180x180-e1663915949148.jpg\" class=\"\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-client-slider-item swiper-slide \">\n\t\t\t\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t\t\t\t<div class=\"single-client image-switcher\" title=\"Qilu Pharmaceuticals\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-image\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"180\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/download_180x180.jpg\" class=\"\" alt=\"\" srcset=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/download_180x180.jpg 180w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/download_180x180-150x150.jpg 150w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-client-slider-item swiper-slide \">\n\t\t\t\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t\t\t\t<div class=\"single-client image-switcher\" title=\"Jayco Chemical\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-image\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"180\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/jayco-logo_180x180.jpg\" class=\"\" alt=\"\" srcset=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/jayco-logo_180x180.jpg 180w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/jayco-logo_180x180-150x150.jpg 150w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-client-slider-item swiper-slide \">\n\t\t\t\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t\t\t\t<div class=\"single-client image-switcher\" title=\"Caltron\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-image\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"180\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/download_1_180x180.jpg\" class=\"\" alt=\"\" srcset=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/download_1_180x180.jpg 180w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/download_1_180x180-150x150.jpg 150w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-client-slider-item swiper-slide \">\n\t\t\t\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t\t\t\t<div class=\"single-client image-switcher\" title=\"Shilpa Healthcare\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-image\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"180\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/shilpa-medicare_180x180.jpg\" class=\"\" alt=\"\" srcset=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/shilpa-medicare_180x180.jpg 180w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/shilpa-medicare_180x180-150x150.jpg 150w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-client-slider-item swiper-slide \">\n\t\t\t\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t\t\t\t<div class=\"single-client image-switcher\" title=\"Emcure\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-image\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"180\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/download_2_180x180.png\" class=\"\" alt=\"\" srcset=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/download_2_180x180.png 180w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/download_2_180x180-150x150.png 150w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-client-slider-item swiper-slide \">\n\t\t\t\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t\t\t\t<div class=\"single-client image-switcher\" title=\"Optimus Pharma\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-image\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"180\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/images_180x180.jpg\" class=\"\" alt=\"\" srcset=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/images_180x180.jpg 180w, https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/images_180x180-150x150.jpg 150w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div><!-- .elementskit-clients-slider END -->\n\t\t<\/div>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c48c60 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c48c60\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e0c772e\" data-id=\"e0c772e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-508c2f9 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"508c2f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;4&quot;,&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/icons8-ledger-64.png\" alt=\"Commercial\" \/><figcaption class=\"elementor-image-carousel-caption\">Commercial<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/icons8-delivered-64.png\" alt=\"Logistics\" \/><figcaption class=\"elementor-image-carousel-caption\">Logistics<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/icons8-rent-64.png\" alt=\"Business Development\" \/><figcaption class=\"elementor-image-carousel-caption\">Business Development<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/icons8-cash-receipt-64.png\" alt=\"Finance\" \/><figcaption class=\"elementor-image-carousel-caption\">Finance<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/09\/icons8-omnichannel-64.png\" alt=\"Marketing\" \/><figcaption class=\"elementor-image-carousel-caption\">Marketing<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3617f09f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3617f09f\" data-element_type=\"section\" data-e-type=\"section\" id=\"xs_fun_3\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d47d32\" data-id=\"7d47d32\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7382f0a7 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"7382f0a7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-43d23b9\" data-id=\"43d23b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a8b5386 elementor-widget elementor-widget-elementskit-funfact\" data-id=\"2a8b5386\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-funfact.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n\t\t<div class=\"elementskit-funfact text-center     \">\n\t\t\t\n\t\t\t<div class=\"elementskit-funfact-inner position_top\">\n\t\t\t\t\t\t\t\t\t<div class=\"funfact-icon\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/elementor\/thumbs\/Shooting-Archery-pui8ghzaxqgb8gt9uiw9pptnxgj37rwg8qj3m64wpe.jpg\" title=\"Shooting Archery\" alt=\"Shooting Archery\" loading=\"lazy\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"funfact-content\">\n\t\t\t\t\t<div class=\"number-percentage-wraper\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"number-percentage\"\n\t\t\t\t\t\t      data-value=\"3125\"\n\t\t\t\t\t\t      data-animation-duration=\"3500\"\n\t\t\t\t\t\t\t  data-style=\"static\">0<\/span>\n\t\t\t\t\t\t+\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<h3 class=\"funfact-title\">Completed Projects<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\n\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6eef2af8\" data-id=\"6eef2af8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57df2fb6 elementor-widget elementor-widget-elementskit-funfact\" data-id=\"57df2fb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-funfact.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n\t\t<div class=\"elementskit-funfact text-center     \">\n\t\t\t\n\t\t\t<div class=\"elementskit-funfact-inner position_top\">\n\t\t\t\t\t\t\t\t\t<div class=\"funfact-icon\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/elementor\/thumbs\/customer-pui7pv7wt6hh7jnf3lfjs1a9c85016iose3rlkg4fo.png\" title=\"customer\" alt=\"customer\" loading=\"lazy\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"funfact-content\">\n\t\t\t\t\t<div class=\"number-percentage-wraper\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"number-percentage\"\n\t\t\t\t\t\t      data-value=\"25523\"\n\t\t\t\t\t\t      data-animation-duration=\"3500\"\n\t\t\t\t\t\t\t  data-style=\"static\">0<\/span>\n\t\t\t\t\t\t+\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<h3 class=\"funfact-title\">Customers<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\n\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-73c9f30d\" data-id=\"73c9f30d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-265775c3 elementor-widget elementor-widget-elementskit-funfact\" data-id=\"265775c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-funfact.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n\t\t<div class=\"elementskit-funfact text-center     \">\n\t\t\t\n\t\t\t<div class=\"elementskit-funfact-inner position_top\">\n\t\t\t\t\t\t\t\t\t<div class=\"funfact-icon\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/elementor\/thumbs\/share-pui87ym2dd96pbd8fx009ywp08yd7fco9y796bmano.png\" title=\"share\" alt=\"share\" loading=\"lazy\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"funfact-content\">\n\t\t\t\t\t<div class=\"number-percentage-wraper\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"number-percentage\"\n\t\t\t\t\t\t      data-value=\"1234\"\n\t\t\t\t\t\t      data-animation-duration=\"3500\"\n\t\t\t\t\t\t\t  data-style=\"static\">0<\/span>\n\t\t\t\t\t\t+\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<h3 class=\"funfact-title\">Suppliers<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\n\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1855159b\" data-id=\"1855159b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96f35ab elementor-widget elementor-widget-elementskit-funfact\" data-id=\"96f35ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-funfact.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n\t\t<div class=\"elementskit-funfact text-center     \">\n\t\t\t\n\t\t\t<div class=\"elementskit-funfact-inner position_top\">\n\t\t\t\t\t\t\t\t\t<div class=\"funfact-icon\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/elementor\/thumbs\/stock_-pui8sukyqdcxs0vgqd2sz3mowpnpclxhlv3rm1toya.jpg\" title=\"stock_\" alt=\"stock_\" loading=\"lazy\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"funfact-content\">\n\t\t\t\t\t<div class=\"number-percentage-wraper\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"number-percentage\"\n\t\t\t\t\t\t      data-value=\"394\"\n\t\t\t\t\t\t      data-animation-duration=\"3500\"\n\t\t\t\t\t\t\t  data-style=\"static\">0<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<h3 class=\"funfact-title\">Active Products<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\n\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d6b965 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d6b965\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e9c7d1a\" data-id=\"e9c7d1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b68f06c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b68f06c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6a5f986\" data-id=\"6a5f986\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49f17f2 elementor-widget elementor-widget-heading\" data-id=\"49f17f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quick Links<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87be974 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"87be974\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c562aa elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9c562aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/iris.com.pk\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Home<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/iris.com.pk\/index.php\/about-us\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">About<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/iris.com.pk\/index.php\/services\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Services<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/iris.com.pk\/index.php\/our-partners\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Our Partners<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/iris.com.pk\/index.php\/contact-us\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Contact<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-435e7eb\" data-id=\"435e7eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61603f7 elementor-widget elementor-widget-heading\" data-id=\"61603f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contact Info<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d091efe elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d091efe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-219c1b2 elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"219c1b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">43-10-e Dr. Mahmood Husain Road, Block 6 PECHS, Karachi, Karachi City, Sindh 75400<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+92 301 8271188<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+92 302 8271188<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+92 21 343 02421<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@iris.com.pk<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2f2eb1b\" data-id=\"2f2eb1b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-731fa6f elementor-widget elementor-widget-shortcode\" data-id=\"731fa6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><iframe style=\"filter: invert(90%)\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m8!1m3!1d14479.218064618715!2d67.0655517!3d24.8705253!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x0%3A0xc8d5b8999336d8fd!2sIRIS%20INTERNATIONAL!5e0!3m2!1sen!2s!4v1662634209029!5m2!1sen!2s\" width=\"450\" height=\"350\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c06417c elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c06417c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-be7f725\" data-id=\"be7f725\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6077b83 elementor-widget elementor-widget-image\" data-id=\"6077b83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"95\" src=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/02\/iris_3-removebg-preview.png\" class=\"attachment-large size-large wp-image-1470\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-464a0b3\" data-id=\"464a0b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9481ed6 elementor-widget elementor-widget-elementskit-social-media\" data-id=\"9481ed6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-social-media.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t\t <ul class=\"ekit_social_media\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-f392861\">\n\t\t\t\t\t    <a\n\t\t\t\t\t\thref=\"https:\/\/www.facebook.com\/pages\/category\/Pharmaceuticals\/Iris-International-790938807623655\/\" aria-label=\"Facebook\" class=\"facebook\" >\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-facebook\"><\/i>\n                                                                                                            <\/a>\n                    <\/li>\n                    \t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-2f3c4eb\">\n\t\t\t\t\t    <a\n\t\t\t\t\t\thref=\"https:\/\/www.linkedin.com\/company\/iris-international\/\" aria-label=\"Linkedin\" class=\"linkedin\" >\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-linkedin\"><\/i>\n                                                                                                            <\/a>\n                    <\/li>\n                    \t\t\t\t\t\t\t<\/ul>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b8e154d\" data-id=\"b8e154d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d45f84 elementor-widget elementor-widget-text-editor\" data-id=\"0d45f84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Copyright \u00a9 2022 IRIS International. All rights reserved<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>info@iris.com.pk 43-10-e Dr. Mahmood Husain Road, Block 6 PECHS, Karachi, Karachi City, Sindh 75400 info@iris.com.pk THE SENSE OF EXCELLENCE IN WORK Home About Us Our portfolio Product Services Our Partners Events Contact Us THE SENSE OF EXCELLENCE IN WORK Home About Us Our portfolio Product Services Our Partners Events Contact Us X ABOUT US ABOUT [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-129","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>About Us - Iris International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iris.com.pk\/index.php\/about-us\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About Us - Iris International\" \/>\n<meta property=\"og:description\" content=\"info@iris.com.pk 43-10-e Dr. Mahmood Husain Road, Block 6 PECHS, Karachi, Karachi City, Sindh 75400 info@iris.com.pk THE SENSE OF EXCELLENCE IN WORK Home About Us Our portfolio Product Services Our Partners Events Contact Us THE SENSE OF EXCELLENCE IN WORK Home About Us Our portfolio Product Services Our Partners Events Contact Us X ABOUT US ABOUT [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iris.com.pk\/index.php\/about-us\/\" \/>\n<meta property=\"og:site_name\" content=\"Iris International\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-22T12:22:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/07\/Untitled-1-01-1-e1657188070788-768x416.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iris.com.pk\\\/index.php\\\/about-us\\\/\",\"url\":\"https:\\\/\\\/iris.com.pk\\\/index.php\\\/about-us\\\/\",\"name\":\"About Us - Iris International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iris.com.pk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/iris.com.pk\\\/index.php\\\/about-us\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/iris.com.pk\\\/index.php\\\/about-us\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iris.com.pk\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Untitled-1-01-1-e1657188070788-768x416.jpg\",\"datePublished\":\"2022-02-03T06:34:30+00:00\",\"dateModified\":\"2022-10-22T12:22:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iris.com.pk\\\/index.php\\\/about-us\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iris.com.pk\\\/index.php\\\/about-us\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/iris.com.pk\\\/index.php\\\/about-us\\\/#primaryimage\",\"url\":\"https:\\\/\\\/iris.com.pk\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Untitled-1-01-1-e1657188070788.jpg\",\"contentUrl\":\"https:\\\/\\\/iris.com.pk\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Untitled-1-01-1-e1657188070788.jpg\",\"width\":1000,\"height\":542},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iris.com.pk\\\/index.php\\\/about-us\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/iris.com.pk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About Us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iris.com.pk\\\/#website\",\"url\":\"https:\\\/\\\/iris.com.pk\\\/\",\"name\":\"Iris International\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/iris.com.pk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About Us - Iris International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iris.com.pk\/index.php\/about-us\/","og_locale":"en_US","og_type":"article","og_title":"About Us - Iris International","og_description":"info@iris.com.pk 43-10-e Dr. Mahmood Husain Road, Block 6 PECHS, Karachi, Karachi City, Sindh 75400 info@iris.com.pk THE SENSE OF EXCELLENCE IN WORK Home About Us Our portfolio Product Services Our Partners Events Contact Us THE SENSE OF EXCELLENCE IN WORK Home About Us Our portfolio Product Services Our Partners Events Contact Us X ABOUT US ABOUT [&hellip;]","og_url":"https:\/\/iris.com.pk\/index.php\/about-us\/","og_site_name":"Iris International","article_modified_time":"2022-10-22T12:22:24+00:00","og_image":[{"url":"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/07\/Untitled-1-01-1-e1657188070788-768x416.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/iris.com.pk\/index.php\/about-us\/","url":"https:\/\/iris.com.pk\/index.php\/about-us\/","name":"About Us - Iris International","isPartOf":{"@id":"https:\/\/iris.com.pk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iris.com.pk\/index.php\/about-us\/#primaryimage"},"image":{"@id":"https:\/\/iris.com.pk\/index.php\/about-us\/#primaryimage"},"thumbnailUrl":"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/07\/Untitled-1-01-1-e1657188070788-768x416.jpg","datePublished":"2022-02-03T06:34:30+00:00","dateModified":"2022-10-22T12:22:24+00:00","breadcrumb":{"@id":"https:\/\/iris.com.pk\/index.php\/about-us\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iris.com.pk\/index.php\/about-us\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/iris.com.pk\/index.php\/about-us\/#primaryimage","url":"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/07\/Untitled-1-01-1-e1657188070788.jpg","contentUrl":"https:\/\/iris.com.pk\/wp-content\/uploads\/2022\/07\/Untitled-1-01-1-e1657188070788.jpg","width":1000,"height":542},{"@type":"BreadcrumbList","@id":"https:\/\/iris.com.pk\/index.php\/about-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/iris.com.pk\/"},{"@type":"ListItem","position":2,"name":"About Us"}]},{"@type":"WebSite","@id":"https:\/\/iris.com.pk\/#website","url":"https:\/\/iris.com.pk\/","name":"Iris International","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iris.com.pk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/iris.com.pk\/index.php\/wp-json\/wp\/v2\/pages\/129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iris.com.pk\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iris.com.pk\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iris.com.pk\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/iris.com.pk\/index.php\/wp-json\/wp\/v2\/comments?post=129"}],"version-history":[{"count":645,"href":"https:\/\/iris.com.pk\/index.php\/wp-json\/wp\/v2\/pages\/129\/revisions"}],"predecessor-version":[{"id":5334,"href":"https:\/\/iris.com.pk\/index.php\/wp-json\/wp\/v2\/pages\/129\/revisions\/5334"}],"wp:attachment":[{"href":"https:\/\/iris.com.pk\/index.php\/wp-json\/wp\/v2\/media?parent=129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}